{"id":6378,"date":"2024-09-26T18:50:48","date_gmt":"2024-09-26T23:50:48","guid":{"rendered":"https:\/\/plenus.edu.mx\/?p=6378"},"modified":"2024-09-26T18:50:49","modified_gmt":"2024-09-26T23:50:49","slug":"curso-de-verano-3er-semana","status":"publish","type":"post","link":"https:\/\/plenus.edu.mx\/blog\/curso-de-verano-3er-semana\/","title":{"rendered":"Curso de Verano 3er Semana"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Curso de Verano 3er Semana\" src=\"https:\/\/player.vimeo.com\/video\/991706157?dnt=1&amp;app_id=122963\" width=\"800\" height=\"450\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":14,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6378","post","type-post","status-publish","format-standard","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/posts\/6378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/comments?post=6378"}],"version-history":[{"count":1,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/posts\/6378\/revisions"}],"predecessor-version":[{"id":6379,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/posts\/6378\/revisions\/6379"}],"wp:attachment":[{"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/media?parent=6378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/categories?post=6378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plenus.edu.mx\/blog\/wp-json\/wp\/v2\/tags?post=6378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}